{"id":50229,"date":"2026-07-14T20:11:47","date_gmt":"2026-07-15T01:11:47","guid":{"rendered":"https:\/\/interpolitico.com\/inicio\/?p=50229"},"modified":"2026-07-14T20:11:47","modified_gmt":"2026-07-15T01:11:47","slug":"ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador","status":"publish","type":"post","link":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/","title":{"rendered":"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador"},"content":{"rendered":"\n<p>Bogot\u00e1, D. C., 14 de julio de 2026. El senador Didier Lobo Chinchilla, del partido Cambio Radical, recibi\u00f3 este martes la credencial que lo acredita oficialmente como Senador de la Rep\u00fablica para el per\u00edodo constitucional 2026\u20132030, consolidando as\u00ed su tercer per\u00edodo consecutivo en el Congreso de la Rep\u00fablica.<\/p>\n\n\n\n<p>Tras recibir el documento expedido por el Consejo Nacional Electoral, el congresista agradeci\u00f3 a Dios, a su familia y a los m\u00e1s de 92 mil colombianos que respaldaron su candidatura en las urnas, destacando que esta nueva responsabilidad representa un compromiso renovado con el pa\u00eds.<\/p>\n\n\n\n<p>\u00abHoy no solo recibo una credencial; renuevo el compromiso de seguir trabajando con la misma dedicaci\u00f3n, cercan\u00eda y responsabilidad durante los pr\u00f3ximos cuatro a\u00f1os. Seguir\u00e9 cumpli\u00e9ndole a Colombia\u00bb, expres\u00f3 el senador.<\/p>\n\n\n\n<p>Lobo Chinchilla asegur\u00f3 que asume este nuevo per\u00edodo con la satisfacci\u00f3n del deber cumplido durante sus ocho a\u00f1os de trayectoria legislativa y con el prop\u00f3sito de continuar impulsando iniciativas que se conviertan en leyes, gestionando para las regiones y defendiendo las causas que contribuyan al desarrollo de Colombia.<\/p>\n\n\n\n<p>El senador tomar\u00e1 posesi\u00f3n de su cargo el pr\u00f3ximo 20 de julio, en la instalaci\u00f3n del nuevo per\u00edodo constitucional del Congreso de la Rep\u00fablica.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"488\" src=\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg\" alt=\"\" class=\"wp-image-50230\" srcset=\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg 650w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-400x300.jpg 400w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-250x188.jpg 250w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-768x576.jpg 768w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-1536x1152.jpg 1536w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-2048x1536.jpg 2048w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-150x113.jpg 150w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-800x600.jpg 800w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-1200x900.jpg 1200w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-1600x1200.jpg 1600w, https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-2000x1500.jpg 2000w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bogot\u00e1, D. C., 14 de julio de 2026. El senador Didier Lobo Chinchilla, del partido Cambio Radical, recibi\u00f3 este martes la credencial que lo acredita oficialmente como Senador de la Rep\u00fablica para el per\u00edodo constitucional 2026\u20132030, consolidando as\u00ed su tercer per\u00edodo consecutivo en el Congreso de la Rep\u00fablica. Tras recibir el documento expedido por el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador - InterPolitico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador - InterPolitico\" \/>\n<meta property=\"og:description\" content=\"Bogot\u00e1, D. C., 14 de julio de 2026. El senador Didier Lobo Chinchilla, del partido Cambio Radical, recibi\u00f3 este martes la credencial que lo acredita oficialmente como Senador de la Rep\u00fablica para el per\u00edodo constitucional 2026\u20132030, consolidando as\u00ed su tercer per\u00edodo consecutivo en el Congreso de la Rep\u00fablica. Tras recibir el documento expedido por el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\" \/>\n<meta property=\"og:site_name\" content=\"InterPolitico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interpolitico\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T01:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg\" \/>\n<meta name=\"author\" content=\"paul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Interpolitico\" \/>\n<meta name=\"twitter:site\" content=\"@Interpolitico\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"paul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\"},\"author\":{\"name\":\"paul\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/#\/schema\/person\/1a1ac87c05d0e64a550b63f4684b755e\"},\"headline\":\"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador\",\"datePublished\":\"2026-07-15T01:11:47+00:00\",\"dateModified\":\"2026-07-15T01:11:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/#organization\"},\"image\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg\",\"articleSection\":[\"Politica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\",\"url\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\",\"name\":\"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador - InterPolitico\",\"isPartOf\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg\",\"datePublished\":\"2026-07-15T01:11:47+00:00\",\"dateModified\":\"2026-07-15T01:11:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage\",\"url\":\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-scaled.jpg\",\"contentUrl\":\"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/interpolitico.com\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/#website\",\"url\":\"https:\/\/interpolitico.com\/inicio\/\",\"name\":\"InterPolitico\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/interpolitico.com\/inicio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/#organization\",\"name\":\"Interpolitico.com\",\"url\":\"https:\/\/interpolitico.com\/inicio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2020\/05\/logo.jpg\",\"contentUrl\":\"http:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2020\/05\/logo.jpg\",\"width\":460,\"height\":73,\"caption\":\"Interpolitico.com\"},\"image\":{\"@id\":\"https:\/\/interpolitico.com\/inicio\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/interpolitico\/\",\"https:\/\/x.com\/Interpolitico\",\"https:\/\/www.instagram.com\/interpolitico\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/#\/schema\/person\/1a1ac87c05d0e64a550b63f4684b755e\",\"name\":\"paul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/interpolitico.com\/inicio\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f707412d5911be897c7b23a0119e1817?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f707412d5911be897c7b23a0119e1817?s=96&d=mm&r=g\",\"caption\":\"paul\"},\"url\":\"https:\/\/interpolitico.com\/inicio\/author\/paul\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador - InterPolitico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/","og_locale":"es_ES","og_type":"article","og_title":"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador - InterPolitico","og_description":"Bogot\u00e1, D. C., 14 de julio de 2026. El senador Didier Lobo Chinchilla, del partido Cambio Radical, recibi\u00f3 este martes la credencial que lo acredita oficialmente como Senador de la Rep\u00fablica para el per\u00edodo constitucional 2026\u20132030, consolidando as\u00ed su tercer per\u00edodo consecutivo en el Congreso de la Rep\u00fablica. Tras recibir el documento expedido por el [&hellip;]","og_url":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/","og_site_name":"InterPolitico","article_publisher":"https:\/\/www.facebook.com\/interpolitico\/","article_published_time":"2026-07-15T01:11:47+00:00","og_image":[{"url":"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg"}],"author":"paul","twitter_card":"summary_large_image","twitter_creator":"@Interpolitico","twitter_site":"@Interpolitico","twitter_misc":{"Escrito por":"paul","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#article","isPartOf":{"@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/"},"author":{"name":"paul","@id":"https:\/\/interpolitico.com\/inicio\/#\/schema\/person\/1a1ac87c05d0e64a550b63f4684b755e"},"headline":"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador","datePublished":"2026-07-15T01:11:47+00:00","dateModified":"2026-07-15T01:11:47+00:00","mainEntityOfPage":{"@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/"},"wordCount":228,"publisher":{"@id":"https:\/\/interpolitico.com\/inicio\/#organization"},"image":{"@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage"},"thumbnailUrl":"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg","articleSection":["Politica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/","url":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/","name":"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador - InterPolitico","isPartOf":{"@id":"https:\/\/interpolitico.com\/inicio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage"},"image":{"@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage"},"thumbnailUrl":"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-650x488.jpg","datePublished":"2026-07-15T01:11:47+00:00","dateModified":"2026-07-15T01:11:47+00:00","breadcrumb":{"@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#primaryimage","url":"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-scaled.jpg","contentUrl":"https:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2026\/07\/Didierloboproyecto-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/interpolitico.com\/inicio\/ocho-anos-de-resultados-cuatro-mas-de-compromiso-didier-lobo-recibe-su-credencial-como-senador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/interpolitico.com\/inicio\/"},{"@type":"ListItem","position":2,"name":"Ocho a\u00f1os de resultados, cuatro m\u00e1s de compromiso: Didier Lobo recibe su credencial como senador"}]},{"@type":"WebSite","@id":"https:\/\/interpolitico.com\/inicio\/#website","url":"https:\/\/interpolitico.com\/inicio\/","name":"InterPolitico","description":"","publisher":{"@id":"https:\/\/interpolitico.com\/inicio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interpolitico.com\/inicio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/interpolitico.com\/inicio\/#organization","name":"Interpolitico.com","url":"https:\/\/interpolitico.com\/inicio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interpolitico.com\/inicio\/#\/schema\/logo\/image\/","url":"http:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2020\/05\/logo.jpg","contentUrl":"http:\/\/interpolitico.com\/inicio\/wp-content\/uploads\/2020\/05\/logo.jpg","width":460,"height":73,"caption":"Interpolitico.com"},"image":{"@id":"https:\/\/interpolitico.com\/inicio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interpolitico\/","https:\/\/x.com\/Interpolitico","https:\/\/www.instagram.com\/interpolitico\/"]},{"@type":"Person","@id":"https:\/\/interpolitico.com\/inicio\/#\/schema\/person\/1a1ac87c05d0e64a550b63f4684b755e","name":"paul","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interpolitico.com\/inicio\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f707412d5911be897c7b23a0119e1817?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f707412d5911be897c7b23a0119e1817?s=96&d=mm&r=g","caption":"paul"},"url":"https:\/\/interpolitico.com\/inicio\/author\/paul\/"}]}},"_links":{"self":[{"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/posts\/50229"}],"collection":[{"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/comments?post=50229"}],"version-history":[{"count":1,"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/posts\/50229\/revisions"}],"predecessor-version":[{"id":50231,"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/posts\/50229\/revisions\/50231"}],"wp:attachment":[{"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/media?parent=50229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/categories?post=50229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interpolitico.com\/inicio\/wp-json\/wp\/v2\/tags?post=50229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}